{"id":44113,"date":"2026-03-23T17:51:32","date_gmt":"2026-03-23T17:51:32","guid":{"rendered":"https:\/\/www.swiss-pass.ch\/faq\/swiss-travel-pass-flex%e5%92%8cswiss-travel-pass%e6%9c%89%e4%bb%80%e4%b9%88%e5%8c%ba%e5%88%ab%ef%bc%9f\/"},"modified":"2026-03-23T17:51:32","modified_gmt":"2026-03-23T17:51:32","slug":"swiss-travel-pass-flex%e5%92%8cswiss-travel-pass%e6%9c%89%e4%bb%80%e4%b9%88%e5%8c%ba%e5%88%ab%ef%bc%9f","status":"publish","type":"bwl_advanced_faq","link":"https:\/\/www.swiss-pass.ch\/zh-hans\/faq\/swiss-travel-pass-flex%e5%92%8cswiss-travel-pass%e6%9c%89%e4%bb%80%e4%b9%88%e5%8c%ba%e5%88%ab%ef%bc%9f\/","title":{"rendered":"Swiss Travel Pass Flex\u548cSwiss Travel Pass\u6709\u4ec0\u4e48\u533a\u522b\uff1f"},"content":{"rendered":"<p>Flex\uff08\u6d3b\u671f\u7248\uff09\uff1a\u4e00\u4e2a\u6708\u5185\u4e0d\u8fde\u7eed\u7684\u65e5\u671f\u3002STP\uff08\u6807\u51c6\u7248\uff09\uff1a\u8fde\u7eed\u7684\u65e5\u671f\u3002Flex\u7684\u4f18\u60e0\uff08\u535a\u7269\u9986\/\u5c71\u533a\uff09\u4ec5\u5728\u6fc0\u6d3b\u7684\u65e5\u671f\u6709\u6548\u3002<\/p>\n<p class=\"faq-read-more\" style=\"margin-top:15px; border-top:1px solid #eee; padding-top:10px;\"><a href=\"https:\/\/www.swiss-pass.ch\/zh-hans\/faq\/swiss-travel-pass-flex%e5%92%8cswiss-travel-pass%e6%9c%89%e4%bb%80%e4%b9%88%e5%8c%ba%e5%88%ab%ef%bc%9f\/\" style=\"font-weight:bold; color:#0073aa; text-decoration:none;\">\u2192 \u67e5\u770b\u5b8c\u6574\u56de\u7b54\u4e0e\u8be6\u60c5<\/a><\/p>","protected":false},"author":9,"parent":0,"template":"","advanced_faq_category":[575],"advanced_faq_topics":[],"class_list":["post-44113","bwl_advanced_faq","type-bwl_advanced_faq","status-publish","hentry","advanced_faq_category-swiss-travel-pass-flex"],"_links":{"self":[{"href":"https:\/\/www.swiss-pass.ch\/zh-hans\/wp-json\/wp\/v2\/bwl_advanced_faq\/44113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.swiss-pass.ch\/zh-hans\/wp-json\/wp\/v2\/bwl_advanced_faq"}],"about":[{"href":"https:\/\/www.swiss-pass.ch\/zh-hans\/wp-json\/wp\/v2\/types\/bwl_advanced_faq"}],"author":[{"embeddable":true,"href":"https:\/\/www.swiss-pass.ch\/zh-hans\/wp-json\/wp\/v2\/users\/9"}],"version-history":[{"count":0,"href":"https:\/\/www.swiss-pass.ch\/zh-hans\/wp-json\/wp\/v2\/bwl_advanced_faq\/44113\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.swiss-pass.ch\/zh-hans\/wp-json\/wp\/v2\/media?parent=44113"}],"wp:term":[{"taxonomy":"advanced_faq_category","embeddable":true,"href":"https:\/\/www.swiss-pass.ch\/zh-hans\/wp-json\/wp\/v2\/advanced_faq_category?post=44113"},{"taxonomy":"advanced_faq_topics","embeddable":true,"href":"https:\/\/www.swiss-pass.ch\/zh-hans\/wp-json\/wp\/v2\/advanced_faq_topics?post=44113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}