{"id":43016,"date":"2026-03-23T17:16:59","date_gmt":"2026-03-23T17:16:59","guid":{"rendered":"https:\/\/www.swiss-pass.ch\/faq\/les-billets-peuvent-ils-etre-annules-2\/"},"modified":"2026-03-23T17:16:59","modified_gmt":"2026-03-23T17:16:59","slug":"les-billets-peuvent-ils-etre-annules-2","status":"publish","type":"bwl_advanced_faq","link":"https:\/\/www.swiss-pass.ch\/fr\/faq\/les-billets-peuvent-ils-etre-annules-2\/","title":{"rendered":"Les billets peuvent-ils \u00eatre annul\u00e9s ?"},"content":{"rendered":"<p>Int\u00e9gralement remboursable uniquement si l'option FLEX CANCELLATION OPTION a \u00e9t\u00e9 achet\u00e9e (annulation >1 jour avant). Sinon, des frais s'appliquent.<\/p>\n<p class=\"faq-read-more\" style=\"margin-top:15px; border-top:1px solid #eee; padding-top:10px;\"><a href=\"https:\/\/www.swiss-pass.ch\/fr\/faq\/les-billets-peuvent-ils-etre-annules-2\/\" style=\"font-weight:bold; color:#0073aa; text-decoration:none;\">\u2192 Voir la r\u00e9ponse compl\u00e8te et les d\u00e9tails<\/a><\/p>","protected":false},"author":9,"parent":0,"template":"","advanced_faq_category":[534],"advanced_faq_topics":[],"class_list":["post-43016","bwl_advanced_faq","type-bwl_advanced_faq","status-publish","hentry","advanced_faq_category-tell-pass"],"_links":{"self":[{"href":"https:\/\/www.swiss-pass.ch\/fr\/wp-json\/wp\/v2\/bwl_advanced_faq\/43016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.swiss-pass.ch\/fr\/wp-json\/wp\/v2\/bwl_advanced_faq"}],"about":[{"href":"https:\/\/www.swiss-pass.ch\/fr\/wp-json\/wp\/v2\/types\/bwl_advanced_faq"}],"author":[{"embeddable":true,"href":"https:\/\/www.swiss-pass.ch\/fr\/wp-json\/wp\/v2\/users\/9"}],"version-history":[{"count":0,"href":"https:\/\/www.swiss-pass.ch\/fr\/wp-json\/wp\/v2\/bwl_advanced_faq\/43016\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.swiss-pass.ch\/fr\/wp-json\/wp\/v2\/media?parent=43016"}],"wp:term":[{"taxonomy":"advanced_faq_category","embeddable":true,"href":"https:\/\/www.swiss-pass.ch\/fr\/wp-json\/wp\/v2\/advanced_faq_category?post=43016"},{"taxonomy":"advanced_faq_topics","embeddable":true,"href":"https:\/\/www.swiss-pass.ch\/fr\/wp-json\/wp\/v2\/advanced_faq_topics?post=43016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}