{"id":43575,"date":"2026-03-23T17:32:29","date_gmt":"2026-03-23T17:32:29","guid":{"rendered":"https:\/\/www.swiss-pass.ch\/faq\/esta-incluido-el-transporte-de-equipaje\/"},"modified":"2026-03-23T17:32:29","modified_gmt":"2026-03-23T17:32:29","slug":"esta-incluido-el-transporte-de-equipaje","status":"publish","type":"bwl_advanced_faq","link":"https:\/\/www.swiss-pass.ch\/es\/faq\/esta-incluido-el-transporte-de-equipaje\/","title":{"rendered":"\u00bfEst\u00e1 incluido el transporte de equipaje?"},"content":{"rendered":"<p>Puede llevar gratuitamente tanto equipaje como pueda cargar. Los trenes tienen portaequipajes. Sin embargo, los servicios de env\u00edo de equipaje puerta a puerta no est\u00e1n incluidos en el pase y deben reservarse por separado a trav\u00e9s de la SBB.<\/p>\n<p class=\"faq-read-more\" style=\"margin-top:15px; border-top:1px solid #eee; padding-top:10px;\"><a href=\"https:\/\/www.swiss-pass.ch\/es\/faq\/esta-incluido-el-transporte-de-equipaje\/\" style=\"font-weight:bold; color:#0073aa; text-decoration:none;\">\u2192 Ver respuesta completa y detalles<\/a><\/p>","protected":false},"author":9,"parent":0,"template":"","advanced_faq_category":[560],"advanced_faq_topics":[],"class_list":["post-43575","bwl_advanced_faq","type-bwl_advanced_faq","status-publish","hentry","advanced_faq_category-consejos-practicos"],"_links":{"self":[{"href":"https:\/\/www.swiss-pass.ch\/es\/wp-json\/wp\/v2\/bwl_advanced_faq\/43575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.swiss-pass.ch\/es\/wp-json\/wp\/v2\/bwl_advanced_faq"}],"about":[{"href":"https:\/\/www.swiss-pass.ch\/es\/wp-json\/wp\/v2\/types\/bwl_advanced_faq"}],"author":[{"embeddable":true,"href":"https:\/\/www.swiss-pass.ch\/es\/wp-json\/wp\/v2\/users\/9"}],"version-history":[{"count":0,"href":"https:\/\/www.swiss-pass.ch\/es\/wp-json\/wp\/v2\/bwl_advanced_faq\/43575\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.swiss-pass.ch\/es\/wp-json\/wp\/v2\/media?parent=43575"}],"wp:term":[{"taxonomy":"advanced_faq_category","embeddable":true,"href":"https:\/\/www.swiss-pass.ch\/es\/wp-json\/wp\/v2\/advanced_faq_category?post=43575"},{"taxonomy":"advanced_faq_topics","embeddable":true,"href":"https:\/\/www.swiss-pass.ch\/es\/wp-json\/wp\/v2\/advanced_faq_topics?post=43575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}