{"id":42447,"date":"2026-03-23T17:03:41","date_gmt":"2026-03-23T17:03:41","guid":{"rendered":"https:\/\/www.swiss-pass.ch\/faq\/reisen-kinder-mit-dem-swiss-travel-pass-flex-kostenlos\/"},"modified":"2026-03-23T17:03:41","modified_gmt":"2026-03-23T17:03:41","slug":"reisen-kinder-mit-dem-swiss-travel-pass-flex-kostenlos","status":"publish","type":"bwl_advanced_faq","link":"https:\/\/www.swiss-pass.ch\/de\/faq\/reisen-kinder-mit-dem-swiss-travel-pass-flex-kostenlos\/","title":{"rendered":"Reisen Kinder mit dem Swiss Travel Pass Flex kostenlos?"},"content":{"rendered":"<p>Kinder bis 16 Jahre reisen mit dem Swiss Travel Pass Flex kostenlos, wenn sie von mindestens einem Elternteil mit der kostenlosen Swiss Family Card begleitet werden.<\/p>\n<p class=\"faq-read-more\" style=\"margin-top:15px; border-top:1px solid #eee; padding-top:10px;\"><a href=\"https:\/\/www.swiss-pass.ch\/de\/faq\/reisen-kinder-mit-dem-swiss-travel-pass-flex-kostenlos\/\" style=\"font-weight:bold; color:#0073aa; text-decoration:none;\">\u2192 Vollst\u00e4ndige Antwort und Details anzeigen<\/a><\/p>","protected":false},"author":9,"parent":0,"template":"","advanced_faq_category":[508],"advanced_faq_topics":[],"class_list":["post-42447","bwl_advanced_faq","type-bwl_advanced_faq","status-publish","hentry","advanced_faq_category-swiss-travel-pass-flex"],"_links":{"self":[{"href":"https:\/\/www.swiss-pass.ch\/de\/wp-json\/wp\/v2\/bwl_advanced_faq\/42447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.swiss-pass.ch\/de\/wp-json\/wp\/v2\/bwl_advanced_faq"}],"about":[{"href":"https:\/\/www.swiss-pass.ch\/de\/wp-json\/wp\/v2\/types\/bwl_advanced_faq"}],"author":[{"embeddable":true,"href":"https:\/\/www.swiss-pass.ch\/de\/wp-json\/wp\/v2\/users\/9"}],"version-history":[{"count":0,"href":"https:\/\/www.swiss-pass.ch\/de\/wp-json\/wp\/v2\/bwl_advanced_faq\/42447\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.swiss-pass.ch\/de\/wp-json\/wp\/v2\/media?parent=42447"}],"wp:term":[{"taxonomy":"advanced_faq_category","embeddable":true,"href":"https:\/\/www.swiss-pass.ch\/de\/wp-json\/wp\/v2\/advanced_faq_category?post=42447"},{"taxonomy":"advanced_faq_topics","embeddable":true,"href":"https:\/\/www.swiss-pass.ch\/de\/wp-json\/wp\/v2\/advanced_faq_topics?post=42447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}